{"id":2306,"count":325,"description":"","link":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/","name":"trda","slug":"trda","taxonomy":"vezava","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>trda Archives - Zavod Iskreni<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"trda Archives - Zavod Iskreni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/\" \/>\n<meta property=\"og:site_name\" content=\"Zavod Iskreni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/vezava\\\/trda\\\/\",\"url\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/vezava\\\/trda\\\/\",\"name\":\"trda Archives - Zavod Iskreni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/vezava\\\/trda\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/vezava\\\/trda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"trda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/#website\",\"url\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/\",\"name\":\"Zavod Iskreni\",\"description\":\"trgovina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iskreni.net\\\/trgovina\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"trda Archives - Zavod Iskreni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/","og_locale":"sl_SI","og_type":"article","og_title":"trda Archives - Zavod Iskreni","og_url":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/","og_site_name":"Zavod Iskreni","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/","url":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/","name":"trda Archives - Zavod Iskreni","isPartOf":{"@id":"https:\/\/www.iskreni.net\/trgovina\/#website"},"breadcrumb":{"@id":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/#breadcrumb"},"inLanguage":"sl-SI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iskreni.net\/trgovina\/vezava\/trda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iskreni.net\/trgovina\/"},{"@type":"ListItem","position":2,"name":"trda"}]},{"@type":"WebSite","@id":"https:\/\/www.iskreni.net\/trgovina\/#website","url":"https:\/\/www.iskreni.net\/trgovina\/","name":"Zavod Iskreni","description":"trgovina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iskreni.net\/trgovina\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"}]}},"_links":{"self":[{"href":"https:\/\/www.iskreni.net\/trgovina\/wp-json\/wp\/v2\/vezava\/2306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iskreni.net\/trgovina\/wp-json\/wp\/v2\/vezava"}],"about":[{"href":"https:\/\/www.iskreni.net\/trgovina\/wp-json\/wp\/v2\/taxonomies\/vezava"}],"wp:post_type":[{"href":"https:\/\/www.iskreni.net\/trgovina\/wp-json\/wp\/v2\/product?vezava=2306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}